{"id":2197,"date":"2025-09-17T17:16:43","date_gmt":"2025-09-17T09:16:43","guid":{"rendered":"https:\/\/jblstainless.com\/?post_type=product&#038;p=2197"},"modified":"2025-09-17T17:16:43","modified_gmt":"2025-09-17T09:16:43","slug":"tubo-senza-saldatura-in-acciaio-inossidabile-316l","status":"publish","type":"product","link":"https:\/\/jblstainless.com\/it\/316l-stainless-steel-seamless-pipe\/","title":{"rendered":"Tubo senza saldatura in acciaio inox 316L"},"content":{"rendered":"<div data-elementor-type=\"product-post\" data-elementor-id=\"2197\" class=\"elementor elementor-2197\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90863c8 e-flex e-con-boxed e-con e-parent\" data-id=\"90863c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-002fb2a elementor-widget elementor-widget-text-editor\" data-id=\"002fb2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il tubo senza saldatura in acciaio inossidabile 316L \u00e8 un tubo in acciaio inossidabile austenitico a basso tenore di carbonio (C\u22640,03%), prodotto con un processo senza saldatura per evitare difetti di saldatura, con 16-18% di cromo, 10-14% di nichel e 2-3% di molibdeno, progettato per applicazioni ad alta corrosione e alta resistenza.<\/p><p>Il tubo senza saldatura 316L \u00e8 la versione a basso tenore di carbonio dell'acciaio inossidabile 316. Il suo design a basso tenore di carbonio riduce al minimo la precipitazione di carburi durante la saldatura, garantendo l'integrit\u00e0 della saldatura ed evitando la corrosione intergranulare. L'acciaio 316L contiene 2-3% di molibdeno, che migliora significativamente la resistenza alla corrosione puntiforme e interstiziale in ambienti salini, acidi o clorurati. Grazie all'eccellente resistenza meccanica e alla resistenza all'ossidazione, il tubo in acciaio inossidabile 316L \u00e8 ampiamente utilizzato in condizioni industriali difficili per garantire un funzionamento affidabile delle apparecchiature a lungo termine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f2659b e-flex e-con-boxed e-con e-parent\" data-id=\"5f2659b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-737b66a elementor-widget elementor-widget-heading\" data-id=\"737b66a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Specifiche dei tubi senza saldatura in acciaio inossidabile 316L<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9360531 elementor-widget elementor-widget-text-editor\" data-id=\"9360531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td>Materiale<\/td><td colspan=\"2\">316L, S31603, 1.4404<\/td><\/tr><tr><td>Standard<\/td><td colspan=\"2\">ASTM A213, ASTM A249, ASTM A269, ASME SA213, ASME SA249, ASME SA269, ecc.<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"4\">Dimensione<\/td><td>Diametro esterno<\/td><td>Da 6 mm a 2500 mm (da 0,25\u2033 a 98\u2033)<\/td><\/tr><tr><td>Spessore della parete<\/td><td><p>Da 0,5 mm a 50 mm<\/p><p>(Sch5, Sch10, Sch40, Sch80, Sch160, ecc.)<\/p><\/td><\/tr><tr><td>Lunghezza<\/td><td><p>3 m, 6 m, 12 m;<\/p><p>Singolo casuale, doppio casuale, standard e lunghezza tagliata<\/p><\/td><\/tr><tr><td colspan=\"2\">dimensioni secondo le richieste del cliente<\/td><\/tr><tr><td colspan=\"1\">Finitura<\/td><td colspan=\"2\"><p>Lucidato, AP (ricotto e decapato), BA (lucido e ricotto), ecc.<\/p><p>BA, 2B, n. 1, 2D, 2B, 8K, HL, ecc.<\/p><\/td><\/tr><tr><td colspan=\"1\">Fine<\/td><td colspan=\"2\">Liscio, smussato, scanalato<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d94d8f e-flex e-con-boxed e-con e-parent\" data-id=\"6d94d8f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4462323 elementor-widget elementor-widget-image\" data-id=\"4462323\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/06\/316-pipe-surface-finish.webp\" class=\"attachment-large size-large wp-image-1669\" alt=\"Tubo in acciaio inox 430\" srcset=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/06\/316-pipe-surface-finish.webp 1000w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/06\/316-pipe-surface-finish-300x150.webp 300w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/06\/316-pipe-surface-finish-768x384.webp 768w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/06\/316-pipe-surface-finish-18x9.webp 18w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/06\/316-pipe-surface-finish-600x300.webp 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd0fe8a elementor-widget elementor-widget-image\" data-id=\"bd0fe8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"223\" src=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/09\/stainless-steel-pipe-end.webp\" class=\"attachment-large size-large wp-image-2201\" alt=\"347 Tubo senza saldatura in acciaio inox\" srcset=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/09\/stainless-steel-pipe-end.webp 1000w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/09\/stainless-steel-pipe-end-700x195.webp 700w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/09\/stainless-steel-pipe-end-768x214.webp 768w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/09\/stainless-steel-pipe-end-18x5.webp 18w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/09\/stainless-steel-pipe-end-600x167.webp 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f39a7b e-con-full e-flex e-con e-parent\" data-id=\"3f39a7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-587b2db elementor-widget elementor-widget-heading\" data-id=\"587b2db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Caratteristiche dei tubi senza saldatura 316L<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fd3f24 elementor-widget elementor-widget-text-editor\" data-id=\"6fd3f24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>1. Resistenza alla corrosione<\/b><\/p><ul><li>Il tubo senza saldatura in acciaio inossidabile 316L ha un'eccellente resistenza alla corrosione, l'aggiunta di elementi di molibdeno per migliorare la resistenza alla corrosione puntiforme e interstiziale, in particolare in presenza di cloruri, alogenuri e ambienti acidi (come acido solforico, acido fosforico, acidi organici), noto anche come \u201cacciaio inossidabile di grado marino\u201d;<\/li><li>ambienti ossidanti (fino a 870 \u00b0C) e l'inquinamento dell'atmosfera oceanica ha un'eccellente stabilit\u00e0.<\/li><\/ul><p><span style=\"font-size: 1rem;\">\u00a0<\/span><\/p><p><span style=\"font-size: 1rem;\"><b>Maggiore resistenza alla corrosione:<\/b>\u00a0<\/span><\/p><p><span style=\"font-size: 1rem;\">La composizione a basso tenore di carbonio con elemento molibdeno agisce in sinergia per superare significativamente la serie 304 nella resistenza alla corrosione da ioni cloruro.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a855af9 elementor-widget elementor-widget-text-editor\" data-id=\"a855af9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>2. Saldabilit\u00e0<br \/><\/b><br \/>Acciaio inossidabile 316L con contenuto di carbonio inferiore a 0,03% per evitare la precipitazione di carburi durante la saldatura, riducendo notevolmente il rischio di sensibilizzazione post-saldatura, il che significa che non \u00e8 necessaria alcuna ricottura aggiuntiva dopo la formazione della saldatura per mantenere la resistenza alla corrosione nell'area di saldatura.<br \/>Inoltre, il materiale 316L presenta una finitura superficiale brillante dopo la lucidatura elettrolitica o il decapaggio e la passivazione ed \u00e8 privo di fonti di contaminazione, soddisfacendo pienamente le specifiche igieniche per le industrie delle camere bianche, alimentare e farmaceutica. Le sue eccellenti caratteristiche di saldatura e pulizia rendono i tubi 316L ideali per i sistemi CIP\/SIP e le linee di trasferimento di fluidi ad alta purezza.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0767324 elementor-widget elementor-widget-text-editor\" data-id=\"0767324\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>3. Sicurezza e affidabilit\u00e0:<\/b><\/p><p>La struttura senza saldature evita il rischio di difetti di saldatura ed \u00e8 adatta a condizioni di lavoro gravose, come quelle dell'industria chimica ed energetica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7a510a elementor-widget elementor-widget-text-editor\" data-id=\"e7a510a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>4. Variet\u00e0 di dimensioni:<\/b><\/p><p>OD 6,0-914,4 mm (\u00e8 possibile personalizzare dimensioni maggiori). Spessore della parete compreso tra 0,3 e 50 mm (SCH5S-SCHXXS). Soddisfa tolleranze rigorose in conformit\u00e0 con gli standard ASME\/ASTM A312. Supporta il taglio personalizzato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e8429d3 e-con-full e-flex e-con e-parent\" data-id=\"e8429d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-752c94e elementor-widget elementor-widget-heading\" data-id=\"752c94e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Controllo qualit\u00e0 dei tubi 316L<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18421b0 elementor-widget elementor-widget-text-editor\" data-id=\"18421b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per garantire una qualit\u00e0 stabile, tutti i nostri tubi sono realizzati con materie prime di alta qualit\u00e0 provenienti da acciaierie rinomate come Baosteel e TISCO. Applichiamo rigorosamente l'intero processo di controllo qualit\u00e0 e forniamo documenti dettagliati quali certificati dell'acciaieria (MTC), composizioni chimiche e rapporti sulle propriet\u00e0 meccaniche.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-adde2bc e-flex e-con-boxed e-con e-parent\" data-id=\"adde2bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4cf8016 elementor-widget elementor-widget-template\" data-id=\"4cf8016\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"single-page\" data-elementor-id=\"738\" class=\"elementor elementor-738\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-1af64ac3 e-flex e-con-boxed e-con e-parent\" data-id=\"1af64ac3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7b59c8f5 e-con-full e-flex e-con e-child\" data-id=\"7b59c8f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-296707c8 elementor-widget elementor-widget-heading\" data-id=\"296707c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ispezione della qualit\u00e0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5cdc1257 e-con-full e-flex e-con e-child\" data-id=\"5cdc1257\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1482c7e1 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1482c7e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/material-test.webp\" class=\"elementor-animation-grow attachment-full size-full wp-image-730\" alt=\"tubi saldati in acciaio stagnato\" srcset=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/material-test.webp 700w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/material-test-600x400.webp 600w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/material-test-300x200.webp 300w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/material-test-18x12.webp 18w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\">Test sui materiali<\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-362fc0eb elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"362fc0eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_2\" tabindex=\"-1\" rel=\"nofollow noopener\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/size-control.webp\" class=\"elementor-animation-grow attachment-full size-full wp-image-731\" alt=\"controllo delle dimensioni del tubo in acciaio inox\" srcset=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/size-control.webp 700w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/size-control-600x400.webp 600w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/size-control-300x200.webp 300w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/size-control-18x12.webp 18w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_2\" rel=\"nofollow noopener\" target=\"_blank\">Controllo delle dimensioni<\/a><\/h4><p class=\"elementor-image-box-description\"> <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bb2e1d5 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7bb2e1d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_3\" tabindex=\"-1\" rel=\"nofollow noopener\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Thickness-test.webp\" class=\"elementor-animation-grow attachment-full size-full wp-image-732\" alt=\"Prova di spessore del tubo d&#039;acciaio\" srcset=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Thickness-test.webp 700w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Thickness-test-600x400.webp 600w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Thickness-test-300x200.webp 300w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Thickness-test-18x12.webp 18w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_3\" rel=\"nofollow noopener\" target=\"_blank\">Test di spessore<\/a><\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b9c7604 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3b9c7604\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_4\" tabindex=\"-1\" rel=\"nofollow noopener\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Ultrasonic-testing.webp\" class=\"elementor-animation-grow attachment-full size-full wp-image-733\" alt=\"Test a ultrasuoni\" srcset=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Ultrasonic-testing.webp 700w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Ultrasonic-testing-600x400.webp 600w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Ultrasonic-testing-300x200.webp 300w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Ultrasonic-testing-18x12.webp 18w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_4\" rel=\"nofollow noopener\" target=\"_blank\">Test a ultrasuoni<\/a><\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57d8e325 e-con-full e-flex e-con e-child\" data-id=\"57d8e325\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69ca4a17 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"69ca4a17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_1\" tabindex=\"-1\" rel=\"nofollow noopener\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Eddy-current-flaw-detection.webp\" class=\"elementor-animation-grow attachment-full size-full wp-image-734\" alt=\"Rilevamento dei difetti a correnti parassite\" srcset=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Eddy-current-flaw-detection.webp 700w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Eddy-current-flaw-detection-600x400.webp 600w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Eddy-current-flaw-detection-300x200.webp 300w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/Eddy-current-flaw-detection-18x12.webp 18w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_1\" rel=\"nofollow noopener\" target=\"_blank\">Rilevamento dei difetti a correnti parassite<\/a><\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69676fde elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"69676fde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_2\" tabindex=\"-1\" rel=\"nofollow noopener\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/watertightness-test.webp\" class=\"elementor-animation-grow attachment-full size-full wp-image-735\" alt=\"test di tenuta all&#039;acqua\" srcset=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/watertightness-test.webp 700w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/watertightness-test-600x400.webp 600w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/watertightness-test-300x200.webp 300w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/watertightness-test-18x12.webp 18w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_2\" rel=\"nofollow noopener\" target=\"_blank\">Test di impermeabilit\u00e0<\/a><\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21b0df4c elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"21b0df4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_3\" tabindex=\"-1\" rel=\"nofollow noopener\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/hardness-test.webp\" class=\"elementor-animation-grow attachment-full size-full wp-image-736\" alt=\"prova di durezza dell&#039;acciaio inossidabile\" srcset=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/hardness-test.webp 700w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/hardness-test-600x400.webp 600w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/hardness-test-300x200.webp 300w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/hardness-test-18x12.webp 18w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_3\" rel=\"nofollow noopener\" target=\"_blank\">Test di durezza<\/a><\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63542480 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"63542480\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_4\" tabindex=\"-1\" rel=\"nofollow noopener\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/tensile-strength.webp\" class=\"elementor-animation-grow attachment-full size-full wp-image-737\" alt=\"resistenza alla trazione\" srcset=\"https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/tensile-strength.webp 700w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/tensile-strength-600x400.webp 600w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/tensile-strength-300x200.webp 300w, https:\/\/jblstainless.com\/wp-content\/uploads\/2025\/02\/tensile-strength-18x12.webp 18w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/library.elementor.com\/local-services-wireframe-1-flexbox\/services\/#service_4\" rel=\"nofollow noopener\" target=\"_blank\">Test di resistenza alla trazione<\/a><\/h4><p class=\"elementor-image-box-description\"> <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d495cad elementor-align-center elementor-widget-mobile__width-inherit elementor-button-info elementor-invisible elementor-widget elementor-widget-button\" data-id=\"6d495cad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjExODMiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" id=\"about\u9875\u9762-1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contattaci<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-787e4eb e-flex e-con-boxed e-con e-parent\" data-id=\"787e4eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69b9c02 elementor-widget elementor-widget-heading\" data-id=\"69b9c02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servizi a valore aggiunto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11d5ecf elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"11d5ecf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Taglio e smussatura personalizzati:<\/b><\/p>\n<p>I tubi 316L possono essere tagliati a lunghezze precise secondo i disegni e smussati o avvitati ad entrambe le estremit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c663f57 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"c663f57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Trattamento della superficie:<\/b><\/p><p>Sono disponibili lucidatura meccanica, lucidatura elettrolitica e passivazione per soddisfare gli elevati requisiti di pulizia delle industrie mediche e alimentari.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c11359 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9c11359\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Ispezione e documentazione:<\/b><\/p><p>Sono disponibili servizi di ispezione quali prove non distruttive, prove di durezza, relazioni di terzi e certificati di qualit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-609861c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"609861c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Confezione:<\/b><\/p><p>Servizi di carico, scarico e imballaggio con esperienza, utilizzando casse di legno standard adatte al trasporto marittimo o imballaggi con reggette in acciaio per garantire che i tubi vengano spediti con la massima protezione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>I tubi senza saldatura in acciaio inossidabile 316L offrono un'eccellente resistenza alla corrosione, particolarmente adatta per ambienti difficili contenenti cloruri (ad esempio acqua di mare, impianti chimici).<\/p>\n<p>Diametro esterno: 3,35 mm \u2013101,6 mm<\/p>\n<p>Spessore della parete: da 0,5 mm a 50 mm (Sch5, Sch10, Sch40, Sch80, Sch160, ecc.)<\/p>\n<p>Lunghezza: 3 m, 6 m, 12 m; singolo casuale, doppio casuale, standard e lunghezza tagliata<\/p>\n<p>Dimensioni secondo le richieste del cliente<\/p>","protected":false},"featured_media":1314,"template":"","meta":{"_eb_attr":""},"product_brand":[],"product_cat":[30],"product_tag":[],"class_list":{"0":"post-2197","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-stainless-steel-seamless-pipe","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/jblstainless.com\/it\/wp-json\/wp\/v2\/product\/2197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jblstainless.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jblstainless.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":7,"href":"https:\/\/jblstainless.com\/it\/wp-json\/wp\/v2\/product\/2197\/revisions"}],"predecessor-version":[{"id":2206,"href":"https:\/\/jblstainless.com\/it\/wp-json\/wp\/v2\/product\/2197\/revisions\/2206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jblstainless.com\/it\/wp-json\/wp\/v2\/media\/1314"}],"wp:attachment":[{"href":"https:\/\/jblstainless.com\/it\/wp-json\/wp\/v2\/media?parent=2197"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jblstainless.com\/it\/wp-json\/wp\/v2\/product_brand?post=2197"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jblstainless.com\/it\/wp-json\/wp\/v2\/product_cat?post=2197"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jblstainless.com\/it\/wp-json\/wp\/v2\/product_tag?post=2197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}